{"id":12237,"date":"2026-02-03T08:57:04","date_gmt":"2026-02-03T07:57:04","guid":{"rendered":"https:\/\/www.78grad.de\/?post_type=buffet&#038;p=12237"},"modified":"2026-02-03T08:57:04","modified_gmt":"2026-02-03T07:57:04","slug":"fingerfood-3","status":"publish","type":"buffet","link":"https:\/\/www.78grad.de\/en\/buffet\/fingerfood-3\/","title":{"rendered":"Fingerfood 3"},"content":{"rendered":"<p class=\"s2\"><strong>Canapes, Mini Wraps &amp; Fingerfoods<\/strong><\/p>\n<p class=\"s2\">\n<ul>\n<li class=\"s2\">Torgauer Landk\u00e4se | Honig-Apfel Chutney | schw. Pfeffer<\/li>\n<li class=\"s2\">lufftgetrocknete Salami | Oliven-Thymian Tapenade<\/li>\n<li class=\"s2\">Spiess von sesam gebeizter Lachs | Limettencreme<\/li>\n<li class=\"s2\">tote Oma |\u00a0Blutwurst | Senfkaviar | Gurken Relish | Kartoffel Chip<\/li>\n<li class=\"s2\">Umami Champignon | Tr\u00fcffel Creme | Sesam | Orange &amp; Thymian<\/li>\n<li class=\"s2\">Rauchtofu | ger\u00f6stete Sesam Sauce | Spinat &amp; Karotten<\/li>\n<li class=\"s2\">Rosmarinschinken | Honig-Senf Creme | Ruccola | eingelgte rote Zwiebeln<\/li>\n<li class=\"s2\">H\u00e4ckerle von Bautzner S\u00fclze | Pumpernickel Erde | eingelegte rote Zwiebeln | Petersilien Schmand<\/li>\n<li class=\"s2\">gezupftes Eisbein | Senfcreme | Creme von frischen Erbsen | Kartoffel Chip<\/li>\n<li class=\"s2\">Leipziger Allerlei |\u00a0Flusskrebse | Kartoffel Creme |\u00a0Morcheln<\/li>\n<\/ul>\n","protected":false},"featured_media":0,"template":"","class_list":["post-12237","buffet","type-buffet","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.78grad.de\/en\/wp-json\/wp\/v2\/buffet\/12237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.78grad.de\/en\/wp-json\/wp\/v2\/buffet"}],"about":[{"href":"https:\/\/www.78grad.de\/en\/wp-json\/wp\/v2\/types\/buffet"}],"wp:attachment":[{"href":"https:\/\/www.78grad.de\/en\/wp-json\/wp\/v2\/media?parent=12237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}